{"id":9451,"date":"2021-10-21T11:45:47","date_gmt":"2021-10-21T09:45:47","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=9451"},"modified":"2021-10-21T11:45:47","modified_gmt":"2021-10-21T09:45:47","slug":"safety-score-outil-evaluation-conduite-tesla","status":"publish","type":"post","link":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/","title":{"rendered":"Safety Score : l\u2019outil d\u2019e\u0301valuation de conduite de Tesla"},"content":{"rendered":"<p>Tesla fait tr\u00e8s certainement partie des entreprises a\u0300 la pointe du de\u0301veloppement technologique dans le secteur automobile. Engage\u0301s en faveur de la transition e\u0301nerge\u0301tique et de l\u2019innovation, l\u2019entreprise ame\u0301ricaine s\u2019est fait conna\u00eetre pour ses mod\u00e8les e\u0301lectriques et ses avance\u0301es vers une conduite autonome.<\/p>\n<h2 style=\"color: #64e600\">Un outil pour rassurer ses conducteurs<\/h2>\n<p>Le syst\u00e8me de conduite autonome Tesla a e\u0301norme\u0301ment fait parler et l\u2019entreprise a re\u00e7u de nombreuses mises en garde vis-a\u0300-vis de la se\u0301curite\u0301 de ces ve\u0301hicules autonomes. Pour l\u2019instant, aucune voiture enti\u00e8rement autonome n\u2019a e\u0301te\u0301 mise en circulation mais Tesla propose l\u2019un des assistants de conduite les plus pousse\u0301s du marche\u0301.<\/p>\n<p>La principale critique faite a\u0300 Tesla est que son assistant a\u0300 la conduite risque de de\u0301responsabiliser le conducteur et le rend moins attentif aux dangers de la route\u2026 Le Safety Score a pour but de re\u0301pondre a\u0300 ce probl\u00e8me en notant la conduite de ses utilisateurs entre 0 et 100 ! Son objectif est de renseigner le conducteur sur les risques potentiels qu\u2019il prend et l\u2019appeler a\u0300 faire preuve de prudence si sa note est trop basse.<\/p>\n<p>Le Safety Score e\u0301value le comportement du conducteur sur la route et estime la probabilite\u0301 qu\u2019il soit responsable d\u2019un accident, le test s\u2019e\u0301tend sur une trentaine de jours.<\/p>\n<h2 style=\"color: #64e600\">Les crit\u00e8res d\u2019e\u0301valuation<\/h2>\n<p>Le Safety Score de Tesla contient un algorithme qui est alimente\u0301 de diffe\u0301rents e\u0301le\u0301ments :<\/p>\n<ul>\n<li>La brutalite\u0301 des freinages : si un ralentissement de\u0301passe une force de 0,3g, il est conside\u0301re\u0301 comme trop tardif ;<\/li>\n<li>L\u2019agressivite\u0301 des virages : pour les virages, la force ressentie doit \u00eatre infe\u0301rieure a\u0300 0,4g ;<\/li>\n<li>Le respect des distances de se\u0301curite\u0301 : le syst\u00e8me e\u0301value la distance laisse\u0301e par le conducteur avec la voiture devant lui ;<\/li>\n<li>Les avertissements de collision : les diffe\u0301rents capteurs de la Tesla sont capables de comptabiliser le nombre de fois que le ve\u0301hicule a d\u00fb signaler un potentiel risque de collision, le Safety Score prend en compte ces alertes ;<\/li>\n<li>L\u2019attention du conducteur : par exemple, si le conducteur retire ses mains du volant alors le ve\u0301hicule e\u0301met un signal sonore avant de de\u0301sactive\u0301 l\u2019assistant \u00ab pilote automatique \u00bb afin d\u2019inviter le conducteur a\u0300 se concentrer pleinement sur sa conduite. Si cette proce\u0301dure est enregistre\u0301e trop souvent par le Safety Score, cela fait baisser le re\u0301sultat du conducteur.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Arrive\u0301e en France et re\u0301ception<\/h2>\n<p>La mise a\u0300 jour ne\u0301cessaire pour obtenir le Safety Score n\u2019a pas encore e\u0301te\u0301 propose\u0301e en France par Tesla et aucune date n\u2019a e\u0301te\u0301 communique\u0301e a\u0300 ce jour. L\u2019entreprise ame\u0301ricaine pre\u0301f\u00e8re certainement tester cette nouvelle fonctionnalite\u0301 a\u0300 domicile avant de l\u2019exporter.<\/p>\n<p>Enfin, le Safety Score pose aussi certaines questions car certains utilisateurs s\u2019inqui\u00e8tent des de\u0301rives potentielles. En effet, la fonctionnalite\u0301 n\u2019offre aucune re\u0301compense aux automobilistes faisant preuve de prudence mais comment s\u2019assurer que les mauvais scores ne seront pas utilise\u0301s contre les conducteurs ? Nous pouvons imaginer que ce type de donne\u0301es pourrait grandement inte\u0301resser les assurances par exemple.<\/p>\n<p>Aujourd\u2019hui, de nombreuses personnes s\u2019opposent aux diffe\u0301rents outils de collecte de donne\u0301es tandis que les entreprises cherchent a\u0300 rassurer sur la mani\u00e8re dont elles seront utilise\u0301es. Dans le cas de Tesla, les donne\u0301es seront probablement utilise\u0301es pour alimenter l\u2019algorithme de l\u2019Autopilot afin d\u2019ame\u0301liorer leur logiciel de conduite autonome !<\/p>\n<p>Pour plus de prudence sur la route, n\u2019he\u0301sitez pas a\u0300 vous munir de <a href=\"https:\/\/www.moncoyote.com\/fr\/application-coyote.html\">l\u2019application Coyote<\/a> sans engagement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tesla fait tr\u00e8s certainement partie des entreprises a\u0300 la pointe du de\u0301veloppement technologique dans le secteur automobile. Engage\u0301s en faveur [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":9455,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12,32],"tags":[],"class_list":["post-9451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automobile","category-innovation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ame\u0301liorer sa conduite avec le Safety Score de Tesla - Le Blog Coyote<\/title>\n<meta name=\"description\" content=\"De\u0301couvrez la nouvelle fonctionnalite\u0301 des Tesla : le Safety Score ! Ame\u0301liorez votre conduite gr\u00e2ce au Safety Score, le logiciel d\u2019e\u0301valuation de conduite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ame\u0301liorer sa conduite avec le Safety Score de Tesla - Le Blog Coyote\" \/>\n<meta property=\"og:description\" content=\"De\u0301couvrez la nouvelle fonctionnalite\u0301 des Tesla : le Safety Score ! Ame\u0301liorez votre conduite gr\u00e2ce au Safety Score, le logiciel d\u2019e\u0301valuation de conduite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog Coyote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/CoyoteFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T09:45:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@coyote_officiel\" \/>\n<meta name=\"twitter:site\" content=\"@coyote_officiel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\"},\"author\":{\"name\":\"Julien\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#\/schema\/person\/4e81cd0174a9bb89856a6d138de888e5\"},\"headline\":\"Safety Score : l\u2019outil d\u2019e\u0301valuation de conduite de Tesla\",\"datePublished\":\"2021-10-21T09:45:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\"},\"wordCount\":642,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png\",\"articleSection\":[\"Automobile\",\"Innovations &amp; Data\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\",\"url\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\",\"name\":\"Ame\u0301liorer sa conduite avec le Safety Score de Tesla - Le Blog Coyote\",\"isPartOf\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png\",\"datePublished\":\"2021-10-21T09:45:47+00:00\",\"description\":\"De\u0301couvrez la nouvelle fonctionnalite\u0301 des Tesla : le Safety Score ! Ame\u0301liorez votre conduite gr\u00e2ce au Safety Score, le logiciel d\u2019e\u0301valuation de conduite.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage\",\"url\":\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png\",\"contentUrl\":\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png\",\"width\":1920,\"height\":1080,\"caption\":\"Personne au volant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.moncoyote.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Automobile\",\"item\":\"https:\/\/www.moncoyote.com\/blog\/automobile\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Safety Score : l\u2019outil d\u2019e\u0301valuation de conduite de Tesla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#website\",\"url\":\"https:\/\/www.moncoyote.com\/blog\/\",\"name\":\"Le Blog Coyote\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.moncoyote.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#organization\",\"name\":\"Coyote\",\"url\":\"https:\/\/www.moncoyote.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2024\/10\/Coyote_Logo_RVB_Logo_Fond_Clair.png\",\"contentUrl\":\"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2024\/10\/Coyote_Logo_RVB_Logo_Fond_Clair.png\",\"width\":1382,\"height\":912,\"caption\":\"Coyote\"},\"image\":{\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr-fr.facebook.com\/CoyoteFrance\",\"https:\/\/x.com\/coyote_officiel\",\"https:\/\/www.instagram.com\/moncoyote\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#\/schema\/person\/4e81cd0174a9bb89856a6d138de888e5\",\"name\":\"Julien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.moncoyote.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/943690b3a1df204b9869db1edfb6c098065b9ec2d3beb314790bdddb0466f31b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/943690b3a1df204b9869db1edfb6c098065b9ec2d3beb314790bdddb0466f31b?s=96&d=mm&r=g\",\"caption\":\"Julien\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ame\u0301liorer sa conduite avec le Safety Score de Tesla - Le Blog Coyote","description":"De\u0301couvrez la nouvelle fonctionnalite\u0301 des Tesla : le Safety Score ! Ame\u0301liorez votre conduite gr\u00e2ce au Safety Score, le logiciel d\u2019e\u0301valuation de conduite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/","og_locale":"fr_FR","og_type":"article","og_title":"Ame\u0301liorer sa conduite avec le Safety Score de Tesla - Le Blog Coyote","og_description":"De\u0301couvrez la nouvelle fonctionnalite\u0301 des Tesla : le Safety Score ! Ame\u0301liorez votre conduite gr\u00e2ce au Safety Score, le logiciel d\u2019e\u0301valuation de conduite.","og_url":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/","og_site_name":"Le Blog Coyote","article_publisher":"https:\/\/fr-fr.facebook.com\/CoyoteFrance","article_published_time":"2021-10-21T09:45:47+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png","type":"image\/png"}],"author":"Julien","twitter_card":"summary_large_image","twitter_creator":"@coyote_officiel","twitter_site":"@coyote_officiel","twitter_misc":{"Written by":"Julien","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#article","isPartOf":{"@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/"},"author":{"name":"Julien","@id":"https:\/\/www.moncoyote.com\/blog\/#\/schema\/person\/4e81cd0174a9bb89856a6d138de888e5"},"headline":"Safety Score : l\u2019outil d\u2019e\u0301valuation de conduite de Tesla","datePublished":"2021-10-21T09:45:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/"},"wordCount":642,"commentCount":1,"publisher":{"@id":"https:\/\/www.moncoyote.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage"},"thumbnailUrl":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png","articleSection":["Automobile","Innovations &amp; Data"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/","url":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/","name":"Ame\u0301liorer sa conduite avec le Safety Score de Tesla - Le Blog Coyote","isPartOf":{"@id":"https:\/\/www.moncoyote.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage"},"image":{"@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage"},"thumbnailUrl":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png","datePublished":"2021-10-21T09:45:47+00:00","description":"De\u0301couvrez la nouvelle fonctionnalite\u0301 des Tesla : le Safety Score ! Ame\u0301liorez votre conduite gr\u00e2ce au Safety Score, le logiciel d\u2019e\u0301valuation de conduite.","breadcrumb":{"@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#primaryimage","url":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png","contentUrl":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2021\/10\/Tesla-safety-score.png","width":1920,"height":1080,"caption":"Personne au volant"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moncoyote.com\/blog\/automobile\/safety-score-outil-evaluation-conduite-tesla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.moncoyote.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Automobile","item":"https:\/\/www.moncoyote.com\/blog\/automobile\/"},{"@type":"ListItem","position":3,"name":"Safety Score : l\u2019outil d\u2019e\u0301valuation de conduite de Tesla"}]},{"@type":"WebSite","@id":"https:\/\/www.moncoyote.com\/blog\/#website","url":"https:\/\/www.moncoyote.com\/blog\/","name":"Le Blog Coyote","description":"","publisher":{"@id":"https:\/\/www.moncoyote.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moncoyote.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.moncoyote.com\/blog\/#organization","name":"Coyote","url":"https:\/\/www.moncoyote.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.moncoyote.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2024\/10\/Coyote_Logo_RVB_Logo_Fond_Clair.png","contentUrl":"https:\/\/medias.coyotesystems.com\/wordpress\/sites\/16\/2024\/10\/Coyote_Logo_RVB_Logo_Fond_Clair.png","width":1382,"height":912,"caption":"Coyote"},"image":{"@id":"https:\/\/www.moncoyote.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/CoyoteFrance","https:\/\/x.com\/coyote_officiel","https:\/\/www.instagram.com\/moncoyote\/"]},{"@type":"Person","@id":"https:\/\/www.moncoyote.com\/blog\/#\/schema\/person\/4e81cd0174a9bb89856a6d138de888e5","name":"Julien","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.moncoyote.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/943690b3a1df204b9869db1edfb6c098065b9ec2d3beb314790bdddb0466f31b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/943690b3a1df204b9869db1edfb6c098065b9ec2d3beb314790bdddb0466f31b?s=96&d=mm&r=g","caption":"Julien"}}]}},"_links":{"self":[{"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/posts\/9451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/comments?post=9451"}],"version-history":[{"count":0,"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/posts\/9451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/media\/9455"}],"wp:attachment":[{"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/media?parent=9451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/categories?post=9451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moncoyote.com\/blog\/wp-json\/wp\/v2\/tags?post=9451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}